{"id":235,"count":2,"description":"","link":"https:\/\/tickle.utk.edu\/mse\/tag\/hahn-choo\/","name":"Hahn Choo","slug":"hahn-choo","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hahn Choo Archives - Materials Science and Engineering<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tickle.utk.edu\/mse\/tag\/hahn-choo\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hahn Choo Archives - Materials Science and Engineering\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tickle.utk.edu\/mse\/tag\/hahn-choo\/\" \/>\n<meta property=\"og:site_name\" content=\"Materials Science and Engineering\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/tickle.utk.edu\\\/mse\\\/tag\\\/hahn-choo\\\/\",\"url\":\"https:\\\/\\\/tickle.utk.edu\\\/mse\\\/tag\\\/hahn-choo\\\/\",\"name\":\"Hahn Choo Archives - Materials Science and Engineering\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tickle.utk.edu\\\/mse\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tickle.utk.edu\\\/mse\\\/tag\\\/hahn-choo\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tickle.utk.edu\\\/mse\\\/tag\\\/hahn-choo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/tickle.utk.edu\\\/mse\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hahn Choo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tickle.utk.edu\\\/mse\\\/#website\",\"url\":\"https:\\\/\\\/tickle.utk.edu\\\/mse\\\/\",\"name\":\"Materials Science and Engineering\",\"description\":\"University of Tennessee, Knoxville\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tickle.utk.edu\\\/mse\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hahn Choo Archives - Materials Science and Engineering","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tickle.utk.edu\/mse\/tag\/hahn-choo\/","og_locale":"en_US","og_type":"article","og_title":"Hahn Choo Archives - Materials Science and Engineering","og_url":"https:\/\/tickle.utk.edu\/mse\/tag\/hahn-choo\/","og_site_name":"Materials Science and Engineering","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/tickle.utk.edu\/mse\/tag\/hahn-choo\/","url":"https:\/\/tickle.utk.edu\/mse\/tag\/hahn-choo\/","name":"Hahn Choo Archives - Materials Science and Engineering","isPartOf":{"@id":"https:\/\/tickle.utk.edu\/mse\/#website"},"breadcrumb":{"@id":"https:\/\/tickle.utk.edu\/mse\/tag\/hahn-choo\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/tickle.utk.edu\/mse\/tag\/hahn-choo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/tickle.utk.edu\/mse\/"},{"@type":"ListItem","position":2,"name":"Hahn Choo"}]},{"@type":"WebSite","@id":"https:\/\/tickle.utk.edu\/mse\/#website","url":"https:\/\/tickle.utk.edu\/mse\/","name":"Materials Science and Engineering","description":"University of Tennessee, Knoxville","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tickle.utk.edu\/mse\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/tickle.utk.edu\/mse\/wp-json\/wp\/v2\/tags\/235","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tickle.utk.edu\/mse\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/tickle.utk.edu\/mse\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/tickle.utk.edu\/mse\/wp-json\/wp\/v2\/posts?tags=235"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}